{"id":5426,"date":"2016-07-13T19:55:00","date_gmt":"2016-07-13T23:55:00","guid":{"rendered":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/"},"modified":"2023-07-24T11:09:27","modified_gmt":"2023-07-24T15:09:27","slug":"merkley-wyden-introduce-legislation-to-address-oil-train-derailments","status":"publish","type":"post","link":"https:\/\/www.merkley.senate.gov\/es\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/","title":{"rendered":"Merkley y Wyden presentan legislaci\u00f3n para abordar los descarrilamientos de trenes petroleros"},"content":{"rendered":"<p>WASHINGTON, DC \u2013 Hoy, los senadores de Oreg\u00f3n Jeff Merkley y Ron Wyden presentaron una legislaci\u00f3n que enfrentar\u00e1 las amenazas que representan los trenes petroleros y ayudar\u00e1 a prevenir accidentes terribles como el que sucedi\u00f3 en Mosier, Oreg\u00f3n el mes pasado. La Ley de Reglas de Emergencia e Inspecciones de Derrames de Petr\u00f3leo por Mandato (MOSIER, por sus siglas en ingl\u00e9s) requerir\u00eda que la Junta Nacional de Seguridad en el Transporte (NTSB, por sus siglas en ingl\u00e9s) investigue todos los descarrilamientos importantes de trenes petroleros, aclare la autoridad de la Administraci\u00f3n Federal de Ferrocarriles para imponer moratorias en el tr\u00e1fico de trenes petroleros cuando ocurran accidentes, y exigir\u00e1 Departamento de Transporte para reducir la cantidad de gases vol\u00e1tiles en el crudo que transportan estos trenes.&nbsp;<\/p>\n<blockquote>\n<p>\u201cComo Oreg\u00f3n ha visto de primera mano, estos trenes petroleros presentan riesgos de explosi\u00f3n\u201d, dijo Merkley. \u201cEso es inaceptable. Necesitamos soluciones a largo plazo que mantengan seguras a las comunidades. Cada accidente necesita ser investigado completa e independientemente. La Administraci\u00f3n Federal de Ferrocarriles debe tener el poder de hacer cumplir las moratorias hasta que los problemas identificados se resuelvan por completo. Y el crudo Bakken altamente explosivo debe estabilizarse antes de que llegue a nuestras comunidades. Este proyecto de ley har\u00e1 los tres, mejorando en gran medida la seguridad a largo plazo\u201d.<\/p>\n<p>\u201cLos habitantes de Oregon merecen las mayores protecciones posibles contra los descarrilamientos de trenes petroleros\u201d, dijo Wyden. \u201cEste proyecto de ley garantiza que las autoridades federales puedan detener los trenes despu\u00e9s de un descarrilamiento importante hasta que se complete una investigaci\u00f3n exhaustiva, y que la NTSB tenga amplios recursos para examinar de cerca las causas fundamentales de tal accidente\u201d.<\/p>\n<\/blockquote>\n<p>La Ley MOSIER que se present\u00f3 hoy:<\/p>\n<ul>\n<li>Exigir a la NTSB que investigue todos los descarrilamientos importantes de trenes petroleros y proporcione recursos para contratar investigadores adicionales.<\/li>\n<li>Aclara la autoridad de la Administraci\u00f3n Federal de Ferrocarriles para poner una moratoria en los trenes unitarios de petr\u00f3leo despu\u00e9s de un accidente para permitir que se completen las investigaciones y se implementen las recomendaciones de seguridad.<\/li>\n<li>Requiere que el Departamento de Transporte establezca y haga cumplir un est\u00e1ndar que reduzca la cantidad de gases vol\u00e1tiles en el petr\u00f3leo crudo. &nbsp;<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>WASHINGTON, D.C. &ndash; Today, Oregon&rsquo;s Senators Jeff Merkley and Ron Wyden introduced legislation that will take on the threats posed by oil trains and help prevent horrific accidents like what happened in Mosier, Oregon last month. The Mandate Oil Spill Inspections and Emergency Rules (MOSIER) Act would require the National Transportation Safety Board (NTSB) to [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[24],"tags":[36],"class_list":["post-5426","post","type-post","status-publish","format-standard","hentry","category-press-releases","tag-natural-resources-and-rural-development"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Merkley, Wyden Introduce Legislation to Address Oil Train Derailments - Merkley<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.merkley.senate.gov\/es\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments - Merkley\" \/>\n<meta property=\"og:description\" content=\"WASHINGTON, D.C. &ndash; Today, Oregon&rsquo;s Senators Jeff Merkley and Ron Wyden introduced legislation that will take on the threats posed by oil trains and help prevent horrific accidents like what happened in Mosier, Oregon last month. The Mandate Oil Spill Inspections and Emergency Rules (MOSIER) Act would require the National Transportation Safety Board (NTSB) to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.merkley.senate.gov\/es\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/\" \/>\n<meta property=\"og:site_name\" content=\"Merkley\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-13T23:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T15:09:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments\",\"datePublished\":\"2016-07-13T23:55:00+00:00\",\"dateModified\":\"2023-07-24T15:09:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/\"},\"wordCount\":329,\"keywords\":[\"Natural Resources and Rural Development\"],\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"es-MX\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/\",\"url\":\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/\",\"name\":\"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments - Merkley\",\"isPartOf\":{\"@id\":\"https:\/\/www.merkley.senate.gov\/#website\"},\"datePublished\":\"2016-07-13T23:55:00+00:00\",\"dateModified\":\"2023-07-24T15:09:27+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.merkley.senate.gov\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.merkley.senate.gov\/#website\",\"url\":\"https:\/\/www.merkley.senate.gov\/\",\"name\":\"Merkley\",\"description\":\"Merkley\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.merkley.senate.gov\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.merkley.senate.gov\/es\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments - Merkley","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.merkley.senate.gov\/es\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/","og_locale":"es_MX","og_type":"article","og_title":"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments - Merkley","og_description":"WASHINGTON, D.C. &ndash; Today, Oregon&rsquo;s Senators Jeff Merkley and Ron Wyden introduced legislation that will take on the threats posed by oil trains and help prevent horrific accidents like what happened in Mosier, Oregon last month. The Mandate Oil Spill Inspections and Emergency Rules (MOSIER) Act would require the National Transportation Safety Board (NTSB) to [&hellip;]","og_url":"https:\/\/www.merkley.senate.gov\/es\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/","og_site_name":"Merkley","article_published_time":"2016-07-13T23:55:00+00:00","article_modified_time":"2023-07-24T15:09:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/#article","isPartOf":{"@id":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/"},"author":{"name":"","@id":""},"headline":"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments","datePublished":"2016-07-13T23:55:00+00:00","dateModified":"2023-07-24T15:09:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/"},"wordCount":329,"keywords":["Natural Resources and Rural Development"],"articleSection":["Press Releases"],"inLanguage":"es-MX"},{"@type":"WebPage","@id":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/","url":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/","name":"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments - Merkley","isPartOf":{"@id":"https:\/\/www.merkley.senate.gov\/#website"},"datePublished":"2016-07-13T23:55:00+00:00","dateModified":"2023-07-24T15:09:27+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.merkley.senate.gov\/merkley-wyden-introduce-legislation-to-address-oil-train-derailments\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.merkley.senate.gov\/"},{"@type":"ListItem","position":2,"name":"Merkley, Wyden Introduce Legislation to Address Oil Train Derailments"}]},{"@type":"WebSite","@id":"https:\/\/www.merkley.senate.gov\/#website","url":"https:\/\/www.merkley.senate.gov\/","name":"merkley","description":"merkley","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.merkley.senate.gov\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Person","@id":"","url":"https:\/\/www.merkley.senate.gov\/es\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/posts\/5426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/comments?post=5426"}],"version-history":[{"count":1,"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/posts\/5426\/revisions"}],"predecessor-version":[{"id":14802,"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/posts\/5426\/revisions\/14802"}],"wp:attachment":[{"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/media?parent=5426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/categories?post=5426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.merkley.senate.gov\/es\/wp-json\/wp\/v2\/tags?post=5426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}